{"id":99494,"date":"2025-05-26T13:24:29","date_gmt":"2025-05-26T17:24:29","guid":{"rendered":"https:\/\/rdvcanada.ca\/?page_id=99494"},"modified":"2025-10-27T15:03:59","modified_gmt":"2025-10-27T19:03:59","slug":"nos-repertoires","status":"publish","type":"page","link":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/","title":{"rendered":"Nos r\u00e9pertoires"},"content":{"rendered":"\n<div id=\"act-rdvc-custom-banner\" class=\"acf-block-component alignfull act-rdvc-custom-banner\" id=\"block-block_6a3479262b16430f71210b4cf59a005e\" className=\"\">\n\n    <div class=\"act-rdvc-custom-banner__overlay\"><\/div>\n\n    <div class=\"act-rdvc-custom-banner__container\">\n        <div class=\"act-rdvc-custom-banner__wrapper\">\n\n                            <h2 class=\"act-rdvc-custom-banner__title fade-in\" aria-label=\"Nos r\u00e9pertoires\" id=\"nos-repertoires\">\n                    Nos r\u00e9pertoires                <\/h2>\n            \n            \n        <\/div>\n\n        <div class=\"act-rdvc-custom-banner__icon fade-in-left\" aria-label=\"Nos r\u00e9pertoires\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"466\" height=\"464\" viewBox=\"0 0 466 464\" fill=\"none\">\n                <path d=\"M459.207 211.681C460.465 210.525 461.352 209.021 461.756 207.358C462.159 205.696 462.061 203.95 461.474 202.344C460.887 200.737 459.837 199.342 458.457 198.335C457.078 197.328 455.431 196.754 453.726 196.686L397.977 194.253C396.849 194.197 395.747 193.897 394.746 193.373C393.744 192.85 392.868 192.116 392.176 191.221C391.484 190.326 390.994 189.292 390.738 188.189C390.483 187.086 390.468 185.941 390.695 184.832L395.941 159.788C396.266 158.169 396.074 156.489 395.392 154.986C394.709 153.484 393.572 152.235 392.141 151.417C390.71 150.6 389.059 150.256 387.421 150.434C385.784 150.612 384.245 151.303 383.022 152.408L316.859 213.409C315.008 215.161 312.61 216.218 310.071 216.401C307.532 216.585 305.008 215.883 302.926 214.414C300.844 212.945 299.332 210.801 298.647 208.343C297.961 205.885 298.143 203.265 299.163 200.926L338.313 106.168C339.179 104.043 339.361 101.699 338.832 99.466C338.303 97.2326 337.089 95.2214 335.362 93.7146C333.634 92.2079 331.48 91.2812 329.201 91.0647C326.921 90.8482 324.632 91.3527 322.653 92.5074L288.671 113.469C287.298 114.32 285.748 114.845 284.141 115.003C282.534 115.161 280.912 114.947 279.4 114.378C277.888 113.81 276.526 112.902 275.418 111.723C274.311 110.545 273.487 109.128 273.011 107.581L243.492 11.8803C242.781 9.59622 241.36 7.59974 239.438 6.18214C237.515 4.76455 235.191 4 232.804 4C230.418 4 228.094 4.76455 226.171 6.18214C224.248 7.59974 222.828 9.59622 222.116 11.8803L192.989 107.581C192.5 109.118 191.669 110.525 190.559 111.694C189.45 112.864 188.09 113.766 186.583 114.333C185.076 114.899 183.46 115.116 181.857 114.966C180.254 114.817 178.706 114.305 177.329 113.469L143.425 92.5074C141.443 91.4037 139.169 90.939 136.914 91.1764C134.659 91.4137 132.531 92.3417 130.82 93.8341C129.109 95.3265 127.898 97.3108 127.352 99.5175C126.805 101.724 126.95 104.046 127.765 106.168L166.915 200.926C167.878 203.269 168.016 205.87 167.307 208.302C166.598 210.734 165.084 212.851 163.014 214.304C160.944 215.758 158.443 216.461 155.921 216.298C153.399 216.136 151.008 215.116 149.141 213.409L83.0565 152.408C81.8335 151.303 80.2939 150.612 78.6567 150.434C77.0195 150.256 75.3681 150.6 73.9372 151.417C72.5063 152.235 71.3689 153.484 70.6866 154.986C70.0044 156.489 69.8121 158.169 70.1371 159.788L75.3831 184.832C75.6111 185.947 75.5945 187.099 75.3344 188.207C75.0742 189.315 74.5768 190.353 73.8766 191.249C73.1765 192.146 72.2903 192.879 71.2795 193.397C70.2687 193.916 69.1575 194.208 68.0229 194.253L12.2738 196.686C10.5686 196.754 8.92194 197.328 7.54253 198.335C6.16312 199.342 5.11321 200.737 4.52601 202.344C3.9388 203.95 3.84076 205.696 4.24435 207.358C4.64793 209.021 5.53493 210.525 6.79282 211.681L47.1953 248.972C48.077 249.814 48.7688 250.835 49.2245 251.967C49.6801 253.099 49.889 254.315 49.8371 255.535C49.7852 256.754 49.4737 257.948 48.9235 259.037C48.3734 260.126 47.5972 261.084 46.6472 261.848L23.9404 279.747C23.0727 280.429 22.3923 281.322 21.9633 282.34C21.5344 283.359 21.371 284.47 21.4885 285.569C21.606 286.669 22.0004 287.72 22.6349 288.624C23.2693 289.528 24.1227 290.256 25.1149 290.738L140.528 346.4C142.313 347.264 143.84 348.585 144.953 350.229C146.067 351.873 146.729 353.783 146.872 355.766C147.015 357.748 146.634 359.733 145.768 361.521C144.901 363.309 143.58 364.836 141.938 365.948L112.34 385.889C110.148 387.334 108.541 389.515 107.807 392.041C107.072 394.566 107.259 397.271 108.333 399.671C109.408 402.071 111.299 404.009 113.669 405.138C116.039 406.266 118.733 406.512 121.267 405.83L221.568 380.865V448.224C221.568 451.347 222.806 454.342 225.008 456.551C227.211 458.759 230.198 460 233.313 460C236.428 460 239.416 458.759 241.618 456.551C243.821 454.342 245.058 451.347 245.058 448.224V380.865L345.438 405.83C347.964 406.477 350.636 406.206 352.982 405.067C355.329 403.927 357.197 401.992 358.256 399.604C359.316 397.216 359.499 394.529 358.772 392.019C358.045 389.509 356.456 387.337 354.286 385.889L324.767 365.948C323.124 364.836 321.803 363.309 320.937 361.521C320.071 359.733 319.69 357.748 319.833 355.766C319.976 353.783 320.637 351.873 321.751 350.229C322.865 348.585 324.391 347.264 326.176 346.4L441.59 290.738C442.582 290.256 443.435 289.528 444.07 288.624C444.704 287.72 445.099 286.669 445.216 285.569C445.334 284.47 445.17 283.359 444.741 282.34C444.312 281.322 443.632 280.429 442.764 279.747L419.979 261.848C419.023 261.086 418.243 260.126 417.692 259.034C417.141 257.941 416.833 256.742 416.788 255.518C416.743 254.295 416.964 253.076 417.433 251.946C417.903 250.816 418.611 249.802 419.509 248.972L459.207 211.681Z\" stroke=\"#F3F3ED\" stroke-width=\"8\" stroke-miterlimit=\"10\"\/>\n            <\/svg>        <\/div>\n    <\/div>\n\n    <?php# if ($svg_icon): ?>\n        <!-- <img decoding=\"async\" class=\"act-rdvc-custom-banner__icon fade-in-left\" src=\"<?php# echo $svg_icon ?>\" alt=\"<?php# echo $title ?>\"> -->\n    <?php# endif; ?>\n\n<\/div>\n\n\n<div class=\"acf-block-component alignfull act-breadcrumb-bar\" id=\"block-block_4e89d04928053828f2ad7a499118e3f7\" className=\"\">\n        <div class=\"wp-block-group alignwide act-breadcrumb-bar__container\">\n            \n            <div class=\"yoast-breadcrumbs\"><span class=\"breadcrumbs\"><a href=\"https:\/\/rdvcanada.ca\/en\/\" class=\"breadcrumbs__element\">Home<\/a> <span class=\"breadcrumbs__separator\">\n        <svg class=\"icon icon-breadcrumb__separator\"><use xlink:href=\"#icon-breadcrumb__separator\"><\/use><\/svg>\n    <\/span> <a href=\"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/\" class=\"breadcrumbs__element\">Cr\u00e9er avec le Canada<\/a> <span class=\"breadcrumbs__separator\">\n        <svg class=\"icon icon-breadcrumb__separator\"><use xlink:href=\"#icon-breadcrumb__separator\"><\/use><\/svg>\n    <\/span> <a href=\"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/\" class=\"breadcrumbs__element\">Avantages et outils<\/a> <span class=\"breadcrumbs__separator\">\n        <svg class=\"icon icon-breadcrumb__separator\"><use xlink:href=\"#icon-breadcrumb__separator\"><\/use><\/svg>\n    <\/span> <span class=\"breadcrumbs__element breadcrumbs__element-current\">Nos r\u00e9pertoires<\/span><\/span><\/div>\n            \n        <\/div>\n    <\/div>\n\n\n\n<p class=\"act-lead wp-block-paragraph\" style=\"margin-bottom:var(--wp--preset--spacing--80)\">Les talents canadiens voyagent \u00e0 travers le monde pour pr\u00e9senter leurs projets lors d\u2019\u00e9v\u00e9nements internationaux. Profitez de ces occasions pour \u00e9tablir des liens, \u00e9changer des id\u00e9es et envisager des collaborations prometteuses.\u00a0<\/p>\n\n\n\n\n<div class=\"wp-block-group alignfull is-style-bg--mapple-grey is-style-bg-mapple-grey is-content-justification-center is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-group is-style-grid-3 is-style-grid-3-special-steps-card is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-right:0;padding-left:0\">\n<div class=\"wp-block-group alignwide is-style-grid-3 is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"js-delegate-link acf-block-component align is-style-default act-card\" id=\"block-block_df6d7334b5f1e2327d8e319e228f6f0a\" className=\"\">\n    <div class=\"act-card__image-wrapper\">\n  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/image2-scaled-1-1.jpg\" alt=\"\" class=\"act-card__image\">\n<\/div>\n    <div class=\"act-card__content\">\n        <p class=\"act-card__badge\">PRODUCTRICES ET PRODUCTEURS<\/p>\n        <h3 class=\"act-card__title\">\n  \n       \n      <a href=\"https:\/\/rdvcanada.ca\/fr\/repertoires\/producteurs\/\"> \n                        <\/a>    \n          <\/h3>\n        <p class=\"act-card__excerpt\">L\u00e0 o\u00f9 se tiennent les grands \u00e9v\u00e9nements, les talents canadiens sont au rendez-vous. Rep\u00e9rez qui est sur place, connectez-vous et posez les bases de collaborations futures. <\/p>\n                        <a href=\"https:\/\/rdvcanada.ca\/fr\/repertoires\/producteurs\/\" class=\"act-card__link\">TROUVER UN PRODUCTEUR<\/a>\n      <\/div>\n<\/div>\n\n\n\n<div class=\"js-delegate-link acf-block-component align is-style-default act-card\" id=\"block-block_31f3ea0520482366a8ab0555f34a1bc5\" className=\"\">\n    <div class=\"act-card__image-wrapper\">\n  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/john-hult-xxgkYSD-ekE-unsplash-scaled-1-1.jpg\" alt=\"\" class=\"act-card__image\" srcset=\"https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/john-hult-xxgkYSD-ekE-unsplash-scaled-1-1.jpg 1980w, https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/john-hult-xxgkYSD-ekE-unsplash-scaled-1-1-648x432.jpg 648w, https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/john-hult-xxgkYSD-ekE-unsplash-scaled-1-1-864x576.jpg 864w, https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/john-hult-xxgkYSD-ekE-unsplash-scaled-1-1-768x512.jpg 768w, https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/john-hult-xxgkYSD-ekE-unsplash-scaled-1-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1980px) 100vw, 1980px\">\n<\/div>\n    <div class=\"act-card__content\">\n        <p class=\"act-card__badge\">SOCI\u00c9T\u00c9S CANADIENNES<\/p>\n        <h3 class=\"act-card__title\">\n  \n       \n      <a href=\"https:\/\/rdvcanada.ca\/fr\/repertoires\/compagnies\/\"> \n                        <\/a>    \n          <\/h3>\n        <p class=\"act-card__excerpt\">Des studios d\u2019effets visuels aux soci\u00e9t\u00e9s de distribution, les soci\u00e9t\u00e9s canadiennes se d\u00e9marquent lors des grands \u00e9v\u00e9nements. D\u00e9couvrez qui est sur place et saisissez l\u2019occasion de cr\u00e9er des liens pour vos projets futurs. <\/p>\n                        <a href=\"https:\/\/rdvcanada.ca\/fr\/repertoires\/compagnies\/\" class=\"act-card__link\">TROUVER UNE SOCI\u00c9T\u00c9<\/a>\n      <\/div>\n<\/div>\n\n\n\n<div class=\"js-delegate-link acf-block-component align is-style-default act-card\" id=\"block-block_86dccb61f281e55f5a1398626ec36511\" className=\"\">\n    <div class=\"act-card__image-wrapper\">\n  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/osarugue-igbinoba-FpWaEa2_d5w-unsplash-scaled-1-1.jpg\" alt=\"\" class=\"act-card__image\" srcset=\"https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/osarugue-igbinoba-FpWaEa2_d5w-unsplash-scaled-1-1.jpg 1980w, https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/osarugue-igbinoba-FpWaEa2_d5w-unsplash-scaled-1-1-768x432.jpg 768w, https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/osarugue-igbinoba-FpWaEa2_d5w-unsplash-scaled-1-1-1024x576.jpg 1024w, https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/osarugue-igbinoba-FpWaEa2_d5w-unsplash-scaled-1-1-220x124.jpg 220w, https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/osarugue-igbinoba-FpWaEa2_d5w-unsplash-scaled-1-1-1536x864.jpg 1536w, https:\/\/rdvcanada.ca\/wp-content\/uploads\/2025\/05\/osarugue-igbinoba-FpWaEa2_d5w-unsplash-scaled-1-1-1920x1080.jpg 1920w\" sizes=\"(max-width: 1980px) 100vw, 1980px\">\n<\/div>\n    <div class=\"act-card__content\">\n        <p class=\"act-card__badge\">PROJETS DE COPRODUCTION<\/p>\n        <h3 class=\"act-card__title\">\n  \n       \n      <a href=\"https:\/\/rdvcanada.ca\/fr\/repertoires\/projets-en-developpement\/\"> \n                        <\/a>    \n          <\/h3>\n        <p class=\"act-card__excerpt\">Les productrices et producteurs canadiens sont \u00e0 la recherche de partenaires pour concr\u00e9tiser leurs projets. Parcourez une s\u00e9lection de coproductions en cours et saisissez l\u2019occasion de b\u00e2tir des collaborations internationales. <\/p>\n                        <a href=\"https:\/\/rdvcanada.ca\/fr\/repertoires\/projets-en-developpement\/\" class=\"act-card__link\">VOIR LES PROJETS EN D\u00c9VELOPPEMENT<\/a>\n      <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"trouvez-les-projets-finances-par-telefilm-les-coproductions-certifiees-et-les-societes-de-coproduction\">Trouvez les projets financ\u00e9s par T\u00e9l\u00e9film, les coproductions certifi\u00e9es et les soci\u00e9t\u00e9s de coproduction.<\/h2>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-style-grid-2 is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-image-fill-element is-style-no-image\"><figure class=\"wp-block-media-text__media\"><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>T\u00c9L\u00c9FILM CANADA<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading is-style-bottom-line\"><strong>R\u00c9PERTOIRE COMPLET DES COPRODUCTIONS<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ayez acc\u00e8s au r\u00e9pertoire complet des coproductions canadiennes officielles sign\u00e9es et de leurs \u00e9quipes de production. Le r\u00e9pertoire de T\u00e9l\u00e9film Canada dresse la liste de toutes les coproductions canadiennes des sept derni\u00e8res ann\u00e9es et est mis \u00e0 jour chaque ann\u00e9e.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/telefilm.ca\/fr\/qui-nous-sommes\/bottins\/bottin-des-coproductions\">EXPLORER LE R\u00c9PERTOIRE DES COPRODUCTIONS SUR TELEFILM.CA<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile is-image-fill-element is-style-no-image-justify-left\"><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><strong>T\u00c9L\u00c9FILM CANADA<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading is-style-bottom-line\" id=\"repertoire-des-societes-de-production\">R\u00c9PERTOIRE DES SOCI\u00c9T\u00c9S DE PRODUCTION<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9couvrez les soci\u00e9t\u00e9s de production qui ont d\u00e9j\u00e0 particip\u00e9 \u00e0 une coproduction cin\u00e9matographique ou t\u00e9l\u00e9visuelle certifi\u00e9e au cours des sept derni\u00e8res ann\u00e9es.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/telefilm.ca\/fr\/qui-nous-sommes\/bottins\/bottin-des-maisons-de-production\">EXPLORER LE R\u00c9PERTOIRE DES SOCI\u00c9T\u00c9S SUR TELEFILM.CA<\/a><\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/rdvcanada.ca\/wp-content\/uploads\/2023\/11\/imageskhjk.png\" alt=\"\" class=\"wp-image-75056 size-full\" style=\"object-position:50% 50%\" loading=\"lazy\" \/><\/figure><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-style-bg-red-erable is-layout-constrained wp-block-group-is-layout-constrained\">\n<div style=\" flex-wrap: nowrap\" class=\" wp-block-group alignwide subscribe__wrapper is-content-justification-space-between is-nowrap is-layout-flex wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group subscribe__container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><strong>Ne manquez rien.<\/strong><\/h2>\n\n\n\n<div style=\" flex-wrap: nowrap\" class=\"wp-block-group is-nowrap is-layout-flex wp-block-group-is-layout-flex\">\n<h1 class=\"wp-block-heading\" id=\"abonnez-vous\">ABONNEZ-VOUS<\/h1>\n\n\n\n<h1 class=\"wp-block-heading is-style-outline\" id=\"maintenant\">MAINTENANT !<\/h1>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Recevez les derni\u00e8res nouvelles du secteur audiovisuel canadien.<\/strong><\/p>\n<\/div>\n\n\n\n<div style=\" flex-wrap: nowrap\" class=\" wp-block-buttons is-horizontal is-content-justification-center is-nowrap is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-light\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/stage.rdvcanada.ca\/fr\/inscription-a-linfolettre\/\" target=\"_blank\" rel=\"noreferrer noopener\">s&#8217;inscrire<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Trouvez les projets financ\u00e9s par T\u00e9l\u00e9film, les coproductions certifi\u00e9es et les soci\u00e9t\u00e9s de coproduction. T\u00c9L\u00c9FILM CANADA R\u00c9PERTOIRE COMPLET DES COPRODUCTIONS Ayez acc\u00e8s au r\u00e9pertoire complet des coproductions canadiennes officielles sign\u00e9es et de leurs \u00e9quipes de production. Le r\u00e9pertoire de T\u00e9l\u00e9film Canada dresse la liste de toutes les coproductions canadiennes des sept derni\u00e8res ann\u00e9es et est&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":99489,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-99494","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9pertoires de notre industrie audiovisuelle | RDV Canada<\/title>\n<meta name=\"description\" content=\"Productrices et producteurs, compagnies de production, projets de coproduction audiovisuels en d\u00e9veloppement : consultez nos r\u00e9pertoires.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9pertoires de notre industrie audiovisuelle | RDV Canada\" \/>\n<meta property=\"og:description\" content=\"Productrices et producteurs, compagnies de production, projets de coproduction audiovisuels en d\u00e9veloppement : consultez nos r\u00e9pertoires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/\" \/>\n<meta property=\"og:site_name\" content=\"RDVCanada.ca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/telefilmcanada\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T19:03:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2023\/11\/imageskhjk.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/avantages-et-outils\\\/nos-repertoires\\\/\",\n\t            \"url\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/avantages-et-outils\\\/nos-repertoires\\\/\",\n\t            \"name\": \"R\u00e9pertoires de notre industrie audiovisuelle | RDV Canada\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/avantages-et-outils\\\/nos-repertoires\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/avantages-et-outils\\\/nos-repertoires\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/rdvcanada.ca\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/imageskhjk.png\",\n\t            \"datePublished\": \"2025-05-26T17:24:29+00:00\",\n\t            \"dateModified\": \"2025-10-27T19:03:59+00:00\",\n\t            \"description\": \"Productrices et producteurs, compagnies de production, projets de coproduction audiovisuels en d\u00e9veloppement : consultez nos r\u00e9pertoires.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/avantages-et-outils\\\/nos-repertoires\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"fr-CA\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/avantages-et-outils\\\/nos-repertoires\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"fr-CA\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/avantages-et-outils\\\/nos-repertoires\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/rdvcanada.ca\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/imageskhjk.png\",\n\t            \"contentUrl\": \"https:\\\/\\\/rdvcanada.ca\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/imageskhjk.png\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/avantages-et-outils\\\/nos-repertoires\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Cr\u00e9er avec le Canada\",\n\t                    \"item\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Avantages et outils\",\n\t                    \"item\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/creer-avec-le-canada\\\/avantages-et-outils\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 4,\n\t                    \"name\": \"Nos r\u00e9pertoires\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/\",\n\t            \"name\": \"RDVCanada.ca\",\n\t            \"description\": \"VOIR GRAND. D\u00e9couvrez le meilleur du talent Canadien \u00e0 travers le monde.\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"fr-CA\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9pertoires de notre industrie audiovisuelle | RDV Canada","description":"Productrices et producteurs, compagnies de production, projets de coproduction audiovisuels en d\u00e9veloppement : consultez nos r\u00e9pertoires.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/","og_locale":"fr_CA","og_type":"article","og_title":"R\u00e9pertoires de notre industrie audiovisuelle | RDV Canada","og_description":"Productrices et producteurs, compagnies de production, projets de coproduction audiovisuels en d\u00e9veloppement : consultez nos r\u00e9pertoires.","og_url":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/","og_site_name":"RDVCanada.ca","article_publisher":"https:\/\/www.facebook.com\/telefilmcanada","article_modified_time":"2025-10-27T19:03:59+00:00","og_image":[{"url":"https:\/\/stage.rdvcanada.ca\/wp-content\/uploads\/2023\/11\/imageskhjk.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/","url":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/","name":"R\u00e9pertoires de notre industrie audiovisuelle | RDV Canada","isPartOf":{"@id":"https:\/\/rdvcanada.ca\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/#primaryimage"},"image":{"@id":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/#primaryimage"},"thumbnailUrl":"https:\/\/rdvcanada.ca\/wp-content\/uploads\/2023\/11\/imageskhjk.png","datePublished":"2025-05-26T17:24:29+00:00","dateModified":"2025-10-27T19:03:59+00:00","description":"Productrices et producteurs, compagnies de production, projets de coproduction audiovisuels en d\u00e9veloppement : consultez nos r\u00e9pertoires.","breadcrumb":{"@id":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/#primaryimage","url":"https:\/\/rdvcanada.ca\/wp-content\/uploads\/2023\/11\/imageskhjk.png","contentUrl":"https:\/\/rdvcanada.ca\/wp-content\/uploads\/2023\/11\/imageskhjk.png"},{"@type":"BreadcrumbList","@id":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/nos-repertoires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rdvcanada.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Cr\u00e9er avec le Canada","item":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/"},{"@type":"ListItem","position":3,"name":"Avantages et outils","item":"https:\/\/rdvcanada.ca\/fr\/creer-avec-le-canada\/avantages-et-outils\/"},{"@type":"ListItem","position":4,"name":"Nos r\u00e9pertoires"}]},{"@type":"WebSite","@id":"https:\/\/rdvcanada.ca\/en\/#website","url":"https:\/\/rdvcanada.ca\/en\/","name":"RDVCanada.ca","description":"VOIR GRAND. D\u00e9couvrez le meilleur du talent Canadien \u00e0 travers le monde.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rdvcanada.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/pages\/99494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=99494"}],"version-history":[{"count":0,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/pages\/99494\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/pages\/99489"}],"wp:attachment":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=99494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}