{"id":8895,"date":"2019-01-10T15:35:43","date_gmt":"2019-01-10T20:35:43","guid":{"rendered":"https:\/\/rdvcanada.ca\/?post_type=movies&#038;p=8895"},"modified":"2021-01-21T15:29:53","modified_gmt":"2021-01-21T20:29:53","slug":"la-course-des-tuques","status":"publish","type":"movies","link":"https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/","title":{"rendered":"La Course des Tuques"},"content":{"rendered":"<p>Fran\u00e7ois les lunettes et ses amis veulent \u00e0 tout prix remporter la course de luge qui s\u2019annonce spectaculaire. Mais Zac, le petit nouveau du village, s\u2019av\u00e8re un adversaire redoutable et sans scrupule.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fran\u00e7ois les lunettes et ses amis veulent \u00e0 tout prix remporter la course de luge qui s\u2019annonce spectaculaire. Mais Zac, le petit nouveau du village, s\u2019av\u00e8re un adversaire redoutable et sans scrupule.<\/p>\n","protected":false},"author":100,"featured_media":0,"parent":0,"menu_order":0,"template":"","festival_prescence_type":[],"festival_festival":[495],"movies_directories":[327],"movies_status":[],"movies_kinds":[63],"movies_presence_name":[],"class_list":["post-8895","movies","type-movies","status-publish","hentry","festival_festival-berlin-2019-fr","movies_kinds-comedie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Course des Tuques - Production audiovisuelle canadienne<\/title>\n<meta name=\"description\" content=\"Obtenez toutes les informations utiles sur ce produit de contenu audiovisuel : genre, r\u00e9alisation, maison de production, etc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Course des Tuques - Production audiovisuelle canadienne\" \/>\n<meta property=\"og:description\" content=\"Obtenez toutes les informations utiles sur ce produit de contenu audiovisuel : genre, r\u00e9alisation, maison de production, etc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/\" \/>\n<meta property=\"og:site_name\" content=\"RDVCanada.ca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/telefilmcanada\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-21T20:29:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/produit\\\/la-course-des-tuques\\\/\",\n\t            \"url\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/produit\\\/la-course-des-tuques\\\/\",\n\t            \"name\": \"La Course des Tuques - Production audiovisuelle canadienne\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2019-01-10T20:35:43+00:00\",\n\t            \"dateModified\": \"2021-01-21T20:29:53+00:00\",\n\t            \"description\": \"Obtenez toutes les informations utiles sur ce produit de contenu audiovisuel : genre, r\u00e9alisation, maison de production, etc.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/produit\\\/la-course-des-tuques\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"fr-CA\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/produit\\\/la-course-des-tuques\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/produit\\\/la-course-des-tuques\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"La Course des Tuques\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/\",\n\t            \"name\": \"RDVCanada.ca\",\n\t            \"description\": \"VOIR GRAND. D\u00e9couvrez le meilleur du talent Canadien \u00e0 travers le monde.\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"fr-CA\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Course des Tuques - Production audiovisuelle canadienne","description":"Obtenez toutes les informations utiles sur ce produit de contenu audiovisuel : genre, r\u00e9alisation, maison de production, etc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/","og_locale":"fr_CA","og_type":"article","og_title":"La Course des Tuques - Production audiovisuelle canadienne","og_description":"Obtenez toutes les informations utiles sur ce produit de contenu audiovisuel : genre, r\u00e9alisation, maison de production, etc.","og_url":"https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/","og_site_name":"RDVCanada.ca","article_publisher":"https:\/\/www.facebook.com\/telefilmcanada","article_modified_time":"2021-01-21T20:29:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/","url":"https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/","name":"La Course des Tuques - Production audiovisuelle canadienne","isPartOf":{"@id":"https:\/\/rdvcanada.ca\/en\/#website"},"datePublished":"2019-01-10T20:35:43+00:00","dateModified":"2021-01-21T20:29:53+00:00","description":"Obtenez toutes les informations utiles sur ce produit de contenu audiovisuel : genre, r\u00e9alisation, maison de production, etc.","breadcrumb":{"@id":"https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rdvcanada.ca\/fr\/produit\/la-course-des-tuques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rdvcanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"La Course des Tuques"}]},{"@type":"WebSite","@id":"https:\/\/rdvcanada.ca\/en\/#website","url":"https:\/\/rdvcanada.ca\/en\/","name":"RDVCanada.ca","description":"VOIR GRAND. D\u00e9couvrez le meilleur du talent Canadien \u00e0 travers le monde.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rdvcanada.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/movies\/8895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/movies"}],"about":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/types\/movies"}],"author":[{"embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/users\/100"}],"version-history":[{"count":0,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/movies\/8895\/revisions"}],"wp:attachment":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=8895"}],"wp:term":[{"taxonomy":"festival_prescence_type","embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/festival_prescence_type?post=8895"},{"taxonomy":"festival_festival","embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/festival_festival?post=8895"},{"taxonomy":"movies_directories","embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/movies_directories?post=8895"},{"taxonomy":"movies_status","embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/movies_status?post=8895"},{"taxonomy":"movies_kinds","embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/movies_kinds?post=8895"},{"taxonomy":"movies_presence_name","embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/movies_presence_name?post=8895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}