{"id":12123,"date":"2018-08-08T10:00:13","date_gmt":"2018-08-08T14:00:13","guid":{"rendered":"https:\/\/rdvcanada.ca\/?post_type=companies&#038;p=12123"},"modified":"2025-11-19T11:56:31","modified_gmt":"2025-11-19T16:56:31","slug":"aux-mode","status":"publish","type":"companies","link":"https:\/\/rdvcanada.ca\/fr\/repertoires\/compagnies\/aux-mode\/","title":{"rendered":"Aux Mode"},"content":{"rendered":"<p>Entreprise de distribution de contenu en ligne se sp\u00e9cialisant dans la mon\u00e9tisation d\u2019IP vol\u00e9es. Nos clients\u00a0: des studios et des distributeurs d\u2019Hollywood (t\u00e9l\u00e9, film, industries de la musique). R\u00e9clamation de droits de propri\u00e9t\u00e9 intellectuelle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entreprise de distribution de contenu en ligne se sp\u00e9cialisant dans la mon\u00e9tisation d\u2019IP vol\u00e9es. Nos clients\u00a0: des studios et des distributeurs d\u2019Hollywood (t\u00e9l\u00e9, film, industries de la musique). R\u00e9clamation de droits de propri\u00e9t\u00e9 intellectuelle.<\/p>\n","protected":false},"author":481,"featured_media":0,"parent":0,"menu_order":0,"template":"","festival_festival":[1218,593,1779,1990,858,371],"class_list":["post-12123","companies","type-companies","status-publish","hentry","festival_festival-berlin-2023-fr","festival_festival-cannes-2019-fr","festival_festival-content-london-2024-fr","festival_festival-content-london-2025-fr","festival_festival-kidscreen-2021-fr","festival_festival-mipcom2018-fr","companies_type-distribution","companies_type-distribution-fr","companies_type-services","companies_type-services-fr","companies_sector-animation-fr","companies_sector-animation","companies_sector-childrenyouth","companies_sector-divertissement","companies_sector-documentaire","companies_sector-documentary","companies_sector-educatif","companies_sector-educational","companies_sector-entertainment","companies_sector-fiction-fr","companies_sector-fiction","companies_sector-film-de-genre-horreur-suspense-etc","companies_sector-genre-horror-thriller-etc","companies_sector-jeunesse","companies_media-digital-media","companies_media-nouveau-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aux Mode - Compagnie audiovisuelle canadienne<\/title>\n<meta name=\"description\" content=\"Obtenez toutes les informations sur Aux Mode, leurs coordonn\u00e9es ainsi que leurs derniers projets compl\u00e9t\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rdvcanada.ca\/en\/repertoires\/compagnies\/aux-mode\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aux Mode - Compagnie audiovisuelle canadienne\" \/>\n<meta property=\"og:description\" content=\"Obtenez toutes les informations sur Aux Mode, leurs coordonn\u00e9es ainsi que leurs derniers projets compl\u00e9t\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rdvcanada.ca\/en\/repertoires\/compagnies\/aux-mode\/\" \/>\n<meta property=\"og:site_name\" content=\"RDVCanada.ca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/telefilmcanada\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T16:56:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/repertoires\\\/compagnies\\\/aux-mode\\\/\",\n\t            \"url\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/repertoires\\\/compagnies\\\/aux-mode\\\/\",\n\t            \"name\": \"Aux Mode - Compagnie audiovisuelle canadienne\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2018-08-08T14:00:13+00:00\",\n\t            \"dateModified\": \"2025-11-19T16:56:31+00:00\",\n\t            \"description\": \"Obtenez toutes les informations sur Aux Mode, leurs coordonn\u00e9es ainsi que leurs derniers projets compl\u00e9t\u00e9s.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/repertoires\\\/compagnies\\\/aux-mode\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"fr-CA\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/repertoires\\\/compagnies\\\/aux-mode\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/repertoires\\\/compagnies\\\/aux-mode\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/rdvcanada.ca\\\/fr\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Companies\",\n\t                    \"item\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/creating-with-canada\\\/find-creative-partners\\\/companies\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Aux Mode\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/\",\n\t            \"name\": \"RDVCanada.ca\",\n\t            \"description\": \"VOIR GRAND. D\u00e9couvrez le meilleur du talent Canadien \u00e0 travers le monde.\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/rdvcanada.ca\\\/en\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"fr-CA\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aux Mode - Compagnie audiovisuelle canadienne","description":"Obtenez toutes les informations sur Aux Mode, leurs coordonn\u00e9es ainsi que leurs derniers projets compl\u00e9t\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rdvcanada.ca\/en\/repertoires\/compagnies\/aux-mode\/","og_locale":"fr_CA","og_type":"article","og_title":"Aux Mode - Compagnie audiovisuelle canadienne","og_description":"Obtenez toutes les informations sur Aux Mode, leurs coordonn\u00e9es ainsi que leurs derniers projets compl\u00e9t\u00e9s.","og_url":"https:\/\/rdvcanada.ca\/en\/repertoires\/compagnies\/aux-mode\/","og_site_name":"RDVCanada.ca","article_publisher":"https:\/\/www.facebook.com\/telefilmcanada","article_modified_time":"2025-11-19T16:56:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rdvcanada.ca\/en\/repertoires\/compagnies\/aux-mode\/","url":"https:\/\/rdvcanada.ca\/en\/repertoires\/compagnies\/aux-mode\/","name":"Aux Mode - Compagnie audiovisuelle canadienne","isPartOf":{"@id":"https:\/\/rdvcanada.ca\/en\/#website"},"datePublished":"2018-08-08T14:00:13+00:00","dateModified":"2025-11-19T16:56:31+00:00","description":"Obtenez toutes les informations sur Aux Mode, leurs coordonn\u00e9es ainsi que leurs derniers projets compl\u00e9t\u00e9s.","breadcrumb":{"@id":"https:\/\/rdvcanada.ca\/en\/repertoires\/compagnies\/aux-mode\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rdvcanada.ca\/en\/repertoires\/compagnies\/aux-mode\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rdvcanada.ca\/en\/repertoires\/compagnies\/aux-mode\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rdvcanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Companies","item":"https:\/\/rdvcanada.ca\/en\/creating-with-canada\/find-creative-partners\/companies\/"},{"@type":"ListItem","position":3,"name":"Aux Mode"}]},{"@type":"WebSite","@id":"https:\/\/rdvcanada.ca\/en\/#website","url":"https:\/\/rdvcanada.ca\/en\/","name":"RDVCanada.ca","description":"VOIR GRAND. D\u00e9couvrez le meilleur du talent Canadien \u00e0 travers le monde.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rdvcanada.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/companies\/12123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/companies"}],"about":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/types\/companies"}],"author":[{"embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/users\/481"}],"version-history":[{"count":0,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/companies\/12123\/revisions"}],"wp:attachment":[{"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=12123"}],"wp:term":[{"taxonomy":"festival_festival","embeddable":true,"href":"https:\/\/rdvcanada.ca\/fr\/wp-json\/wp\/v2\/festival_festival?post=12123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}